{"id":36,"date":"2020-02-06T12:24:13","date_gmt":"2020-02-06T12:24:13","guid":{"rendered":"http:\/\/gradasediciones.com\/?p=36"},"modified":"2020-10-06T12:27:11","modified_gmt":"2020-10-06T12:27:11","slug":"helen-beatrix-potter","status":"publish","type":"post","link":"https:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/","title":{"rendered":"Helen Beatrix Potter"},"content":{"rendered":"\n<p>(28 de julio de 1866 \u2013 22 de diciembre de 1943)<\/p>\n\n\n\n<p>Escritora, ilustradora, naturalista y conservacionista inglesa que no solo cre\u00f3 una galer\u00eda de personajes animales que se incrustaron en el imaginario cultural occidental por su ternura y sencillez -con el famoso&nbsp;<em>Peter Rabbit<\/em>&nbsp;a la cabeza-, sino que desafi\u00f3 el mandato patriarcal de su \u00e9poca con una serie de acciones que a\u00fan hoy causan asombro y admiraci\u00f3n.<\/p>\n\n\n\n<p>Criada en un acomodado hogar brit\u00e1nico, hizo de su curiosidad y brillantez intelectual un estilo de vida que todav\u00eda repercute a trav\u00e9s de la obra art\u00edstica-cient\u00edfica que dej\u00f3 como legado.<\/p>\n\n\n\n<p>Ms. Potter sigue siendo una de las autoras infantiles m\u00e1s vendidas de la historia:&nbsp;<strong>escribi\u00f3 e ilustr\u00f3 28 libros que han sido traducidos a m\u00e1s de 35 idiomas de los cuales se vendieron m\u00e1s de 100 millones de copias<\/strong>.<\/p>\n\n\n\n<p>Estas obras brillan por una visi\u00f3n na\u00edf del mundo pero a la vez patentaron un estilo imitado pero nunca igualado. Su est\u00e9tica se basa en un estilo naturalista de los paisajes campestres ingleses, a base de dibujos hechos en acuarela -t\u00e9cnica muy utilizada a finales del siglo XIX- que muchas veces choca con partes de las historias en que dejan de ser dulces para ser crueles e incluso ir\u00f3nicas en su retrato de la sociedad de una \u00e9poca.<\/p>\n\n\n\n<p>A pesar de haber obtenido su Certificado de Arte para el dibujo, lleg\u00f3 a los 21 a\u00f1os con muy poca educaci\u00f3n. Y como muchas hijas adultas de los ricos, fue nombrada \u201csupervisora \u200b\u200bdel hogar\u201d, un rol que le dej\u00f3 suficiente tiempo para satisfacer su inter\u00e9s en las ciencias naturales. Se convirti\u00f3 en una talentosa naturalista. Hizo estudios de plantas y animales en los museos de Cromwell Road, y aprendi\u00f3 a dibujar con un microscopio.<\/p>\n\n\n\n<p>Ilustraba tarjetas de saludos y tambi\u00e9n hab\u00eda comenzado a escribir cartas ilustradas a los ni\u00f1os de su antigua institutriz.&nbsp;<em>Peter Rabbit<\/em>&nbsp;naci\u00f3 en una carta que escribi\u00f3 en septiembre de 1893. Siete a\u00f1os despu\u00e9s, pidi\u00f3 prestada la carta y copi\u00f3 las ilustraciones para producir una versi\u00f3n aproximada de lo que se convertir\u00eda en<strong><em>&nbsp;El cuento de Peter Rabbit. Dibujado en el futuro<\/em><\/strong>. En 1901, despu\u00e9s de que seis editores rechazaron su trabajo, ella lo public\u00f3 de manera autogestionada (250 ejemplares) para regalarlo a sus familiares y conocidos. Fue un \u00e9xito y la editorial Frederick Warne &amp; Co. cambi\u00f3 de parecer y public\u00f3&nbsp;<strong><em>The Tale of Peter Rabbit<\/em><\/strong>&nbsp;con un \u00e9xito de ventas que super\u00f3 todas las expectativa. Tras este libro vinieron muchos m\u00e1s.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"440\" height=\"475\" src=\"http:\/\/gradasediciones.com\/wp-content\/uploads\/2020\/10\/Conejo-Peter-Rabbit.jpg\" alt=\"\" class=\"wp-image-38\" srcset=\"https:\/\/gradasediciones.com\/wp-content\/uploads\/2020\/10\/Conejo-Peter-Rabbit.jpg 440w, https:\/\/gradasediciones.com\/wp-content\/uploads\/2020\/10\/Conejo-Peter-Rabbit-278x300.jpg 278w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>(28 de julio de 1866 \u2013 22 de diciembre de 1943) Escritora, ilustradora, naturalista y conservacionista inglesa que no solo &hellip; <a class=\"more-link\" href=\"https:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/\">More<\/a><\/p>\n","protected":false},"author":1,"featured_media":37,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"jetpack_featured_media_url":"https:\/\/gradasediciones.com\/wp-content\/uploads\/2020\/10\/Beatrix-Potter.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Helen Beatrix Potter - Gradas Ediciones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Helen Beatrix Potter - Gradas Ediciones\" \/>\n<meta property=\"og:description\" content=\"(28 de julio de 1866 \u2013 22 de diciembre de 1943) Escritora, ilustradora, naturalista y conservacionista inglesa que no solo &hellip; More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/\" \/>\n<meta property=\"og:site_name\" content=\"Gradas Ediciones\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gradasediciones\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-06T12:24:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-06T12:27:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gradasediciones.com\/wp-content\/uploads\/2020\/10\/Beatrix-Potter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GradasEdiciones\" \/>\n<meta name=\"twitter:site\" content=\"@GradasEdiciones\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/gradasediciones.com\/#organization\",\"name\":\"Gradas Ediciones\",\"url\":\"https:\/\/gradasediciones.com\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/gradasediciones\",\"https:\/\/twitter.com\/GradasEdiciones\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/gradasediciones.com\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/gradasediciones.com\/wp-content\/uploads\/2020\/10\/Logo-final-Gradas-Gris-con-aire.jpg\",\"width\":900,\"height\":900,\"caption\":\"Gradas Ediciones\"},\"image\":{\"@id\":\"https:\/\/gradasediciones.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gradasediciones.com\/#website\",\"url\":\"https:\/\/gradasediciones.com\/\",\"name\":\"Gradas Ediciones\",\"description\":\"Lecturas graduadas\",\"publisher\":{\"@id\":\"https:\/\/gradasediciones.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/gradasediciones.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/gradasediciones.com\/wp-content\/uploads\/2020\/10\/Beatrix-Potter.jpg\",\"width\":300,\"height\":168,\"caption\":\"Beatrix Potter Gradas Ediciones\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/#webpage\",\"url\":\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/\",\"name\":\"Helen Beatrix Potter - Gradas Ediciones\",\"isPartOf\":{\"@id\":\"https:\/\/gradasediciones.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/#primaryimage\"},\"datePublished\":\"2020-02-06T12:24:13+00:00\",\"dateModified\":\"2020-10-06T12:27:11+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/\"]}]},{\"@type\":\"Article\",\"@id\":\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/#webpage\"},\"author\":{\"@id\":\"https:\/\/gradasediciones.com\/#\/schema\/person\/7759fb96995725a66b26c1b28910acce\"},\"headline\":\"Helen Beatrix Potter\",\"datePublished\":\"2020-02-06T12:24:13+00:00\",\"dateModified\":\"2020-10-06T12:27:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/gradasediciones.com\/#organization\"},\"image\":{\"@id\":\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/#primaryimage\"},\"articleSection\":\"Autores\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/gradasediciones.com\/index.php\/2020\/02\/06\/helen-beatrix-potter\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/gradasediciones.com\/#\/schema\/person\/7759fb96995725a66b26c1b28910acce\",\"name\":\"gradasediciones\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/gradasediciones.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/52d0422f6806529192c8eab70a48b4d8?s=96&d=mm&r=g\",\"caption\":\"gradasediciones\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/posts\/36"}],"collection":[{"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":2,"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/posts\/36\/revisions"}],"predecessor-version":[{"id":40,"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/posts\/36\/revisions\/40"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/media\/37"}],"wp:attachment":[{"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/media?parent=36"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/categories?post=36"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gradasediciones.com\/index.php\/wp-json\/wp\/v2\/tags?post=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}